{"id":5538,"date":"2025-05-26T16:03:46","date_gmt":"2025-05-26T08:03:46","guid":{"rendered":"https:\/\/uniasen.com\/?page_id=5538"},"modified":"2025-05-26T16:10:13","modified_gmt":"2025-05-26T08:10:13","slug":"ul-listed-pipe","status":"publish","type":"page","link":"https:\/\/uniasen.com\/it\/prodotti\/tubo-elencato-ul\/","title":{"rendered":"Tubo antincendio omologato UL"},"content":{"rendered":"<div id=\"page-header-23531112\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark featured-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap\" >\n              <div class=\"title-wrapper flex-col text-left medium-text-center\">\n          <h1 class=\"entry-title mb-0\">\n            Tubo antincendio omologato UL          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col flex-right text-right medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div>\n\n     \n<style>\n#page-header-23531112 .title-bg {\n  background-image: url(https:\/\/uniasen.com\/wp-content\/uploads\/2023\/08\/slide_3-scaled-1.webp);\n}\n<\/style>\n  <\/div>\n    <\/div>\n  \n\n\t<section class=\"section\" id=\"section_77178016\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1817763175\">\n\n\t<div id=\"col-1091474998\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1675140730\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1675140730 {\n  padding-top: 4%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle\"  id=\"row-1271777207\">\n\n\t<div id=\"col-399632121\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1302988669\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/fire-sprinkler-pipes\u200b.webp\" class=\"attachment-original size-original\" alt=\"tubi sprinkler antincendio\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/fire-sprinkler-pipes\u200b.webp 1000w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/fire-sprinkler-pipes\u200b-300x225.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/fire-sprinkler-pipes\u200b-768x576.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/fire-sprinkler-pipes\u200b-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1302988669 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1719338956\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1049090922\" class=\"text\">\n\t\t\n<h2>Tubo antincendio omologato UL<\/h2>\n\t\t\n<style>\n#text-1049090922 {\n  font-size: 1.2rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-222364658\" class=\"text\">\n\t\t\n<p>I tubi antincendio certificati UL sono prodotti che hanno superato i rigorosi test del laboratorio di sicurezza UL negli Stati Uniti. Questi tubi possono trasportare in modo stabile l'acqua o i mezzi di estinzione negli incendi.<\/p>\n<p>La certificazione UL \u00e8 uno standard di sicurezza riconosciuto a livello mondiale, soprattutto in Nord America, Medio Oriente, Sud-Est asiatico e altri luoghi. Questi tubi hanno caratteristiche di robustezza dei materiali, resistenza alla corrosione, resistenza alle alte pressioni e altre propriet\u00e0. I progetti su larga scala richiedono l'uso di prodotti antincendio certificati UL.<\/p>\n<p>I tubi antincendio certificati UL di UNIASEN sono disponibili in diversi tipi: zincati, in acciaio nero e verniciati. Sono conformi agli standard UL 852 e sono ideali per edifici commerciali, fabbriche e magazzini.<br \/>\n\t\t\n<style>\n#text-222364658 {\n  font-size: 1.9rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-50372629\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-50372629 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-197166306\">\n\n\t<div id=\"col-581871671\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"#is-pop\" class=\"button alert\"  style=\"border-radius:9px;\">\n\t\t<span>Preventivo gratuito<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-753304699\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-753304699 {\n  padding-top: 2%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_77178016 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1000693756\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-545784678\">\n\n\t<div id=\"col-191226226\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Tubi antincendio certificati UL per tipo di rivestimento<\/h2>\n<p>Le tubazioni antincendio certificate UL di UNIASEN si concentrano su affidabilit\u00e0 e adattabilit\u00e0. Aiutano gli ingegneri a rispettare le normative e a ridurre i rischi di incendio.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2104980804\">\n\n\t<div id=\"col-2088354895\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Hot-dip-galvanized-UL-certified-fire-pipes.webp\" class=\"attachment- size-\" alt=\"Tubi antincendio zincati a caldo con certificazione UL\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Hot-dip-galvanized-UL-certified-fire-pipes.webp 1000w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Hot-dip-galvanized-UL-certified-fire-pipes-300x225.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Hot-dip-galvanized-UL-certified-fire-pipes-768x576.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Hot-dip-galvanized-UL-certified-fire-pipes-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\t<div id=\"text-1713723346\" class=\"text\">\n\t\t\n<h4>Tubi antincendio zincati a caldo certificati UL<\/h4>\n\t\t\n<style>\n#text-1713723346 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2830556442\" class=\"text\">\n\t\t\n<ul>\n<li>Caratteristiche: Lo strato superficiale zincato aumenta la resistenza alla ruggine ed \u00e8 adatto ad ambienti umidi o altamente corrosivi.<\/li>\n<li>Applicazione: Ampiamente utilizzato negli impianti antincendio all'aperto, negli impianti industriali, ecc.<\/li>\n<\/ul>\n\t\t\n<style>\n#text-2830556442 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1632346608\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Black-UL-certified-fire-pipes.webp\" class=\"attachment- size-\" alt=\"Tubi antincendio neri certificati UL\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Black-UL-certified-fire-pipes.webp 1000w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Black-UL-certified-fire-pipes-300x225.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Black-UL-certified-fire-pipes-768x576.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Black-UL-certified-fire-pipes-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\t<div id=\"text-1858626996\" class=\"text\">\n\t\t\n<h4>Tubi antincendio neri certificati UL<\/h4>\n\t\t\n<style>\n#text-1858626996 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-307744720\" class=\"text\">\n\t\t\n<ul>\n<li>Caratteristiche: I tubi in acciaio non rivestiti, con costi inferiori, sono adatti per ambienti interni asciutti e a bassa corrosione.<\/li>\n<li>Applicazione: Si trova comunemente nelle tubazioni di alimentazione dell'acqua antincendio in magazzini e garage sotterranei.<\/li>\n<\/ul>\n\t\t\n<style>\n#text-307744720 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-897780041\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Painted-UL-certified-fire-pipes.webp\" class=\"attachment- size-\" alt=\"Tubi antincendio verniciati certificati UL\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Painted-UL-certified-fire-pipes.webp 1000w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Painted-UL-certified-fire-pipes-300x225.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Painted-UL-certified-fire-pipes-768x576.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2025\/05\/Painted-UL-certified-fire-pipes-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\t<div id=\"text-195735364\" class=\"text\">\n\t\t\n<h4>Tubi antincendio verniciati certificati UL<\/h4>\n\t\t\n<style>\n#text-195735364 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1849881212\" class=\"text\">\n\t\t\n<ul>\n<li>Caratteristiche: Lo strato esterno \u00e8 rivestito con vernice ignifuga, che combina prevenzione della ruggine e bellezza, e il colore pu\u00f2 essere personalizzato.<\/li>\n<li>Applicazione: Luoghi con requisiti estetici, come centri commerciali e hotel.<\/li>\n<\/ul>\n\t\t\n<style>\n#text-1849881212 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1000693756 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1047440277\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-94423150\">\n\n\t<div id=\"col-1837608454\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1002934274\" class=\"text\">\n\t\t\n<h2>Specifiche e dimensioni<\/h2>\n\t\t\n<style>\n#text-1002934274 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1489536147\">\n\n\t<div id=\"col-1083349963\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li><strong>Materiale Standard:<\/strong> Prodotto secondo gli standard ASTM o gli standard internazionali generali per i tubi d'acciaio.<\/li>\n<li><strong>Tipo di rivestimento:<\/strong> Vernice nera, resina epossidica, zincata, primer rosso, adatti a diversi ambienti.<\/li>\n<li><strong>Gamma di dimensioni:<\/strong> Diametro da 1\/2 pollice a 12 pollici, lunghezza da 5 a 21 piedi<\/li>\n<li><strong>Selezione dello spessore della parete:<\/strong> SCH10\/SCH30\/SCH40, SCH40 ha la parete pi\u00f9 spessa e pu\u00f2 sopportare una pressione di \u2265175 libbre per pollice quadrato.<\/li>\n<li><strong>Trattamento dell'estremit\u00e0 del tubo:<\/strong> Supporta tre metodi di connessione: estremit\u00e0 piatta, scanalatura e filettatura<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1047440277 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n@media (min-width:550px) {\n  #section_1047440277 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2105695551\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-846112924\">\n\n\t<div id=\"col-2029918978\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Dimensioni delle tubazioni antincendio con classificazione UL<\/h2>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1527530201\">\n\n\t<div id=\"col-1218192463\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div style=\"overflow: auto; \" >\n<table border=\"\u201d1\u2033\" width=\"\u201d3000px\u201d\" height=\"\u201d120px\u201d\" align=\"\u201dcenter\u201d\" >\n<thead>\n<tr>\n<th colspan=\"2\" rowspan=\"2\">N.D.<\/th>\n<th colspan=\"2\" rowspan=\"2\">O.D.<\/th>\n<th colspan=\"4\">SCH 10<\/th>\n<th colspan=\"4\">SCH 30\/40<\/th>\n<\/tr>\n<tr>\n<th colspan=\"2\">SPESSORE DELLA PARETE<\/th>\n<th colspan=\"2\">PESO NOMINALE<\/th>\n<th colspan=\"2\">SPESSORE DELLA PARETE<\/th>\n<th colspan=\"2\">PESO NOMINALE<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>(mm)<\/td>\n<td>(Pollici)<\/td>\n<td>(mm)<\/td>\n<td>(Pollici)<\/td>\n<td>(mm)<\/td>\n<td>(Pollici)<\/td>\n<td>(kg\/mtr)<\/td>\n<td>(lbs\/ft)<\/td>\n<td>(mm)<\/td>\n<td>(Pollici)<\/td>\n<td>(kg\/mtr)<\/td>\n<td>(lbs\/ft)<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td> 1\/2<\/td>\n<td>21.3<\/td>\n<td>0.84<\/td>\n<td>--<\/td>\n<td>--<\/td>\n<td>--<\/td>\n<td>--<\/td>\n<td>2.77<\/td>\n<td>0.109<\/td>\n<td>1.27<\/td>\n<td>0.85<\/td>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td> 3\/4<\/td>\n<td>26.7<\/td>\n<td>1.05<\/td>\n<td>2.11<\/td>\n<td>0.083<\/td>\n<td>1.28<\/td>\n<td>0.96<\/td>\n<td>2.87<\/td>\n<td>0.113<\/td>\n<td>1.69<\/td>\n<td>1.13<\/td>\n<\/tr>\n<tr>\n<td>25<\/td>\n<td>1<\/td>\n<td>33.4<\/td>\n<td>1.32<\/td>\n<td>2.77<\/td>\n<td>0.109<\/td>\n<td>2.09<\/td>\n<td>1.41<\/td>\n<td>3.38<\/td>\n<td>0.133<\/td>\n<td>2.5<\/td>\n<td>1.68<\/td>\n<\/tr>\n<tr>\n<td>32<\/td>\n<td>1-1\/4<\/td>\n<td>42.2<\/td>\n<td>1.66<\/td>\n<td>2.77<\/td>\n<td>0.109<\/td>\n<td>2.69<\/td>\n<td>1.81<\/td>\n<td>3.56<\/td>\n<td>0.14<\/td>\n<td>3.39<\/td>\n<td>2.27<\/td>\n<\/tr>\n<tr>\n<td>40<\/td>\n<td>1-1\/2<\/td>\n<td>48.3<\/td>\n<td>1.9<\/td>\n<td>2.77<\/td>\n<td>0.109<\/td>\n<td>3.11<\/td>\n<td>2.09<\/td>\n<td>3.68<\/td>\n<td>0.145<\/td>\n<td>4.05<\/td>\n<td>2.72<\/td>\n<\/tr>\n<tr>\n<td>50<\/td>\n<td>2<\/td>\n<td>60.3<\/td>\n<td>2.38<\/td>\n<td>2.77<\/td>\n<td>0.109<\/td>\n<td>3.93<\/td>\n<td>2.64<\/td>\n<td>3.91<\/td>\n<td>0.154<\/td>\n<td>5.45<\/td>\n<td>3.66<\/td>\n<\/tr>\n<tr>\n<td>65<\/td>\n<td>2-1\/2<\/td>\n<td>73<\/td>\n<td>2.88<\/td>\n<td>3.05<\/td>\n<td>0.12<\/td>\n<td>5.26<\/td>\n<td>3.53<\/td>\n<td>5.16<\/td>\n<td>0.203<\/td>\n<td>8.64<\/td>\n<td>5.8<\/td>\n<\/tr>\n<tr>\n<td>80<\/td>\n<td>3<\/td>\n<td>88.9<\/td>\n<td>3.5<\/td>\n<td>3.05<\/td>\n<td>0.12<\/td>\n<td>6.46<\/td>\n<td>4.34<\/td>\n<td>5.49<\/td>\n<td>0.216<\/td>\n<td>11.29<\/td>\n<td>7.58<\/td>\n<\/tr>\n<tr>\n<td>90<\/td>\n<td>3-1\/2<\/td>\n<td>101.6<\/td>\n<td>4<\/td>\n<td>3.05<\/td>\n<td>0.12<\/td>\n<td>7.41<\/td>\n<td>4.98<\/td>\n<td>5.74<\/td>\n<td>0.226<\/td>\n<td>13.58<\/td>\n<td>9.12<\/td>\n<\/tr>\n<tr>\n<td>100<\/td>\n<td>4<\/td>\n<td>114.3<\/td>\n<td>4.5<\/td>\n<td>3.05<\/td>\n<td>0.12<\/td>\n<td>8.37<\/td>\n<td>5.62<\/td>\n<td>6.02<\/td>\n<td>0.237<\/td>\n<td>16.09<\/td>\n<td>10.8<\/td>\n<\/tr>\n<tr>\n<td>125<\/td>\n<td>5<\/td>\n<td>141.3<\/td>\n<td>5.56<\/td>\n<td>3.4<\/td>\n<td>0.134<\/td>\n<td>11.58<\/td>\n<td>7.78<\/td>\n<td>6.55<\/td>\n<td>0.258<\/td>\n<td>21.79<\/td>\n<td>14.63<\/td>\n<\/tr>\n<tr>\n<td>150<\/td>\n<td>6<\/td>\n<td>168.3<\/td>\n<td>6.63<\/td>\n<td>3.4<\/td>\n<td>0.134<\/td>\n<td>13.85<\/td>\n<td>9.3<\/td>\n<td>7.11<\/td>\n<td>0.28<\/td>\n<td>28.29<\/td>\n<td>18.99<\/td>\n<\/tr>\n<tr>\n<td>200<\/td>\n<td>8<\/td>\n<td>219.1<\/td>\n<td>8.63<\/td>\n<td>4.78<\/td>\n<td>0.188<\/td>\n<td>25.26<\/td>\n<td>16.96<\/td>\n<td>7.04<\/td>\n<td>0.277<\/td>\n<td>36.82<\/td>\n<td>24.72<\/td>\n<\/tr>\n<tr>\n<td>250<\/td>\n<td>10<\/td>\n<td>273.1<\/td>\n<td>10.75<\/td>\n<td>4.78<\/td>\n<td>0.188<\/td>\n<td>31.62<\/td>\n<td>21.23<\/td>\n<td>7.08<\/td>\n<td>0.307<\/td>\n<td>51.05<\/td>\n<td>34.27<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1652097763\">\n\n\t<div id=\"col-2010895599\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"#is-pop\" class=\"button alert\"  style=\"border-radius:9px;\">\n\t\t<span>Richiedi subito un preventivo<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2105695551 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n@media (min-width:550px) {\n  #section_2105695551 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_478276173\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1145593722\">\n\n\t<div id=\"col-271693793\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Requisiti chimici<\/h2>\n<p>Il nostro acciaio per tubi antincendio \u00e8 prodotto rigorosamente secondo rapporti standard. La composizione dell'acciaio dei diversi gradi (A\/B\/C) \u00e8 chiaramente controllata per garantire la resistenza alla ruggine e la durata di vita:<\/p>\n<ul>\n<li><strong>Contenuto di carbonio:<\/strong> non pi\u00f9 di 0,25% per il grado A, non pi\u00f9 di 0,3% per il grado B, e non pi\u00f9 di 0,35% per il grado C<\/li>\n<li><strong>Contenuto di manganese:<\/strong> 0,27%~0,93% per il grado A, 0,29%~1,06% per i gradi B e C<\/li>\n<li><strong>Fosforo e zolfo:<\/strong> non pi\u00f9 di 0,025% per tutte le qualit\u00e0<\/li>\n<li><strong>Contenuto di silicio:<\/strong> minimo 0,1%<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_478276173 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1449266751\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-101105831\">\n\n\t<div id=\"col-638928772\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Propriet\u00e0 meccaniche<\/h2>\n<p>I tubi devono soddisfare gli indicatori di resistenza alla trazione, alla compressione e alla duttilit\u00e0 per garantire che non si deformino o si rompano durante un incendio:<\/p>\n<ul>\n<li><strong>Resistenza alla trazione:<\/strong> Grado A \u226548.000 psi, Grado B \u226560.000 psi, Grado C \u226570.000 psi<\/li>\n<li><strong>Resistenza allo snervamento:<\/strong> Grado A \u226530.000 psi, Grado B \u226535.000 psi, Grado C \u226540.000 psi<\/li>\n<li><strong>Duttilit\u00e0:<\/strong> Tutti i tubi superano il test di piegatura e non presentano crepe dopo la piegatura<\/li>\n<li><strong>Durezza:<\/strong> Soddisfano gli standard UL per evitare danni durante l'installazione<\/li>\n<\/ul>\n<p>I tubi di grado elevato (come il grado C) sono adatti ai sistemi di alimentazione idrica principale ad alta pressione, mentre il grado A pu\u00f2 essere utilizzato nelle aree ordinarie per ridurre i costi.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1449266751 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_208872842\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-162390579\">\n\n\t<div id=\"col-401552660\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-2031493340\">\n\n\t<div id=\"col-1362596029\" class=\"col medium-12 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3945326753\" class=\"text\">\n\t\t\n<h2>Perch\u00e9 scegliere i tubi antincendio certificati UL di UNIASEN?<\/h2>\n\t\t\n<style>\n#text-3945326753 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-530246635\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-530246635 {\n  padding-top: 10px;\n}\n@media (min-width:550px) {\n  #gap-530246635 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<p>Garanzia di certificazione autorevoleI tubi UL hanno superato i test di laboratorio UL e soddisfano gli standard nazionali degli Stati Uniti e del Canada, rispondendo ai rigidi requisiti delle offerte ingegneristiche in molti luoghi del mondo.Capacit\u00e0 di personalizzazione flessibileForniamo una variet\u00e0 di dimensioni (come 2 pollici, 4 pollici) e di tipi di rivestimento, supportiamo la personalizzazione in base alle esigenze ingegneristiche e ci adattiamo a diversi sistemi di protezione antincendio (sprinkler, idranti, ecc.).Controllo di qualit\u00e0 rigorosoDalle materie prime ai prodotti finiti, ogni processo \u00e8 testato secondo gli standard UL e ogni lotto di prodotti \u00e8 campionato e testato per le prestazioni. Le organizzazioni UL controllano regolarmente le linee di produzione per garantire la stabilit\u00e0 della qualit\u00e0 a lungo termine.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1103712665\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"UNIASEN - FORNITURA DI TUBI IN ACCIAIO\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/oDiJnYyLsz4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_208872842 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_76546877\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-2008241377\">\n\n\t<div id=\"col-1316977030\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3286905892\" class=\"text\">\n\t\t\n<h2>Domande frequenti<\/h2>\n\t\t\n<style>\n#text-3286905892 {\n  font-size: 1.2rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"accordion\">\n\t<div id=\"accordion-1320545705\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1320545705-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-does-ul-certification-for-fire-protection-pipes-mean?\" aria-expanded=\"false\" aria-controls=\"accordion-1320545705-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Che cosa significa la certificazione UL per i tubi antincendio?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1320545705-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1320545705-label\" >\n\t\t\t\n<p>La certificazione UL \u00e8 un test di sicurezza eseguito da un'organizzazione terza. In parole povere, serve a verificare se il tubo antincendio soddisfa gli standard di sicurezza e a garantire che possa funzionare correttamente in caso di incendio. Il superamento di questa certificazione significa che il prodotto soddisfa i requisiti di sicurezza riconosciuti dal settore.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2022834133\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2022834133-label\" class=\"accordion-title plain\" href=\"#accordion-item-why-is-ul-certification-so-important-for-fire-protection-pipes?\" aria-expanded=\"false\" aria-controls=\"accordion-2022834133-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Perch\u00e9 la certificazione UL \u00e8 cos\u00ec importante per i tubi antincendio?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2022834133-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2022834133-label\" >\n\t\t\t\n<p>I tubi antincendio sono direttamente collegati alla sicurezza delle persone e dei beni in caso di incendio. Con la certificazione UL, tutti possono fidarsi che questi tubi siano di qualit\u00e0 affidabile e non causino problemi in caso di incendio. Inoltre, in molti luoghi le leggi richiedono l'uso di attrezzature antincendio certificate UL, altrimenti potrebbero essere illegali.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1760511829\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1760511829-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-types-of-ul-certified-fire-protection-pipes-does-uniasen-provide?\" aria-expanded=\"false\" aria-controls=\"accordion-1760511829-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Quali tipi di tubi antincendio certificati UL fornisce UNIASEN?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1760511829-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1760511829-label\" >\n\t\t\t\n<p>I tubi antincendio certificati UL forniti da UNIASEN comprendono tubi in acciaio zincato, tubi in acciaio inox e altri tipi, che coprono diverse dimensioni (come 2 pollici, 4 pollici, ecc.).<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n<div class=\"accordion\">\n\t<div id=\"accordion-1329589053\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1329589053-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-standards-do-ul-certified-fire-protection-pipes-meet?\" aria-expanded=\"false\" aria-controls=\"accordion-1329589053-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>A quali standard rispondono i tubi antincendio certificati UL?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1329589053-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1329589053-label\" >\n\t\t\t\n<p>I tubi antincendio certificati UL soddisfano principalmente standard quali UL 852 UL 2442 (tubi in acciaio zincato) e UL 213 (tubi in acciaio inossidabile).<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2573515157\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2573515157-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-types-of-fire-protection-systems-can-ul-certified-fire-protection-pipes-be-used-for?\" aria-expanded=\"false\" aria-controls=\"accordion-2573515157-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Per quali tipi di sistemi antincendio possono essere utilizzati i tubi antincendio certificati UL?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2573515157-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2573515157-label\" >\n\t\t\t\n<p>Questo tipo di tubo pu\u00f2 essere utilizzato in impianti sprinkler automatici, sistemi di idranti, impianti di estinzione a schiuma, ecc. Che si tratti di un edificio commerciale, di una fabbrica o di un magazzino, se \u00e8 necessaria una protezione antincendio, il tubo pu\u00f2 essere utilizzato.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2859910750\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2859910750-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-is-the-difference-between-schedule-10-and-schedule-40-fire-protection-pipes-listed-by-ul?\" aria-expanded=\"false\" aria-controls=\"accordion-2859910750-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Qual \u00e8 la differenza tra le tubazioni antincendio Schedule 10 e Schedule 40 elencate da UL?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2859910750-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2859910750-label\" >\n\t\t\t\n<p>La differenza principale \u00e8 data dallo spessore della parete del tubo e dalla capacit\u00e0 di sopportare la pressione. I tubi Schedule 10 hanno pareti pi\u00f9 sottili e sono adatti a scenari con pressioni pi\u00f9 basse; i tubi Schedule 40 hanno pareti pi\u00f9 spesse e sono in grado di sopportare pressioni pi\u00f9 elevate, come ad esempio le condotte principali di approvvigionamento idrico o le aree ad alto rischio.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3414173527\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3414173527-label\" class=\"accordion-title plain\" href=\"#accordion-item-how-does-uniasen-ensure-the-quality-of-ul-certified-fire-protection-pipes?\" aria-expanded=\"false\" aria-controls=\"accordion-3414173527-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Attiva\/Disattiva\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Come fa UNIASEN a garantire la qualit\u00e0 dei tubi antincendio certificati UL?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3414173527-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3414173527-label\" >\n\t\t\t\n<ul>\n<li>Utilizziamo materie prime conformi agli standard;<\/li>\n<li>Ogni fase del processo produttivo viene controllata in base ai requisiti UL;<\/li>\n<li>Ogni lotto di prodotti viene testato a campione.<\/li>\n<li>Le organizzazioni UL visitano regolarmente le fabbriche per controlli a campione.<\/li>\n<\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_76546877 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_76546877 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1750402783\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1236894592\">\n\n\t<div id=\"col-448959186\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3275350156\" class=\"text\">\n\t\t\n<h2>Prodotti correlati<\/h2>\n\t\t\n<style>\n#text-3275350156 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_1405259199\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1722494388\">\n\n\n\t<div id=\"col-634429953\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1901880310\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-289648317\">\n\n\n\t<div id=\"col-800369628\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1985958563\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/prodotti\/tubo-erw\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe.webp\" class=\"attachment-original size-original\" alt=\"Cina Tubo ERW produttore\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1985958563 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2827126907\" class=\"text\">\n\t\t\n\n<p><strong>Tubo saldato<\/strong><\/p>\n\t\t\n<style>\n#text-2827126907 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2827126907 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-837760012\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1120626660\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/prodotti\/tubo-per-sega\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe.webp\" class=\"attachment-original size-original\" alt=\"Produttore e fornitore di tubi d&#039;acciaio per sega\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1120626660 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2501397146\" class=\"text\">\n\t\t\n\n<p><strong>Tubo in acciaio SSAW<\/strong><\/p>\n\t\t\n<style>\n#text-2501397146 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2501397146 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-453283107\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_70497877\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/prodotti\/sezioni-cave\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier.webp\" class=\"attachment-original size-original\" alt=\"sezione cava in acciaio-sezione cava strutturale-Uniasen\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_70497877 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3253643928\" class=\"text\">\n\t\t\n\n<p><strong>Sezione strutturale cava<\/strong><\/p>\n\t\t\n<style>\n#text-3253643928 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-3253643928 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1410517009\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2097545787\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/prodotti\/tubo-senza-saldatura\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe.webp\" class=\"attachment-original size-original\" alt=\"tubo d&#039;acciaio senza saldatura - tubo SIML\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_2097545787 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2391694603\" class=\"text\">\n\t\t\n\n<p><strong>Tubo in acciaio senza saldatura<\/strong><\/p>\n\t\t\n<style>\n#text-2391694603 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2391694603 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-333991895\">\n\n\n\t<div id=\"col-461742603\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_974656989\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/prodotti\/raccordi-per-tubi\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer.webp\" class=\"attachment-original size-original\" alt=\"raccordi per tubi in Cina, raccordi per tubi in acciaio al carbonio\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_974656989 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-205794390\" class=\"text\">\n\t\t\n\n<p><strong>Raccordi per tubi Raccordi per tubi<\/strong><\/p>\n\t\t\n<style>\n#text-205794390 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-205794390 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1286780295\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1320442243\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/steel-pipe-standards\/fire-sprinkler-pipe\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1320442243 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-4097004268\" class=\"text\">\n\t\t\n\n<p><strong>Tubo per sprinkler antincendio<\/strong><\/p>\n\t\t\n<style>\n#text-4097004268 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-4097004268 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-531085761\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1469700308\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/steel-pipe-standards\/line-pipe\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1469700308 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2129963006\" class=\"text\">\n\t\t\n\n<p><strong>Tubo di linea<\/strong><\/p>\n\n\t\t\n<style>\n#text-2129963006 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2129963006 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2117361336\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1118174056\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/it\/steel-pipe-standards\/astm-a106\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1118174056 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2067723646\" class=\"text\">\n\t\t\n\n<p><strong>ASTM A106 Tubo in acciaio senza saldatura<\/strong><\/p>\n\t\t\n<style>\n#text-2067723646 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2067723646 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1405259199 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1750402783 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":912,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-5538","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UL Listed Fire Pipe - UNIASEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniasen.com\/it\/prodotti\/tubo-elencato-ul\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UL Listed Fire Pipe - UNIASEN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniasen.com\/it\/prodotti\/tubo-elencato-ul\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIASEN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-26T08:10:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uniasen.com\/products\/ul-listed-pipe\/\",\"url\":\"https:\/\/uniasen.com\/products\/ul-listed-pipe\/\",\"name\":\"UL Listed Fire Pipe - UNIASEN\",\"isPartOf\":{\"@id\":\"https:\/\/uniasen.com\/#website\"},\"datePublished\":\"2025-05-26T08:03:46+00:00\",\"dateModified\":\"2025-05-26T08:10:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/uniasen.com\/products\/ul-listed-pipe\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uniasen.com\/products\/ul-listed-pipe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uniasen.com\/products\/ul-listed-pipe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/uniasen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"products\",\"item\":\"https:\/\/uniasen.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UL Listed Fire Pipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uniasen.com\/#website\",\"url\":\"https:\/\/uniasen.com\/\",\"name\":\"UNIASEN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/uniasen.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uniasen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/uniasen.com\/#organization\",\"name\":\"UniAsen\",\"alternateName\":\"UniAsen (Tianjin) Co., Ltd.\",\"url\":\"https:\/\/uniasen.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/uniasen.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp\",\"contentUrl\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp\",\"width\":300,\"height\":300,\"caption\":\"UniAsen\"},\"image\":{\"@id\":\"https:\/\/uniasen.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UL Listed Fire Pipe - UNIASEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniasen.com\/it\/prodotti\/tubo-elencato-ul\/","og_locale":"it_IT","og_type":"article","og_title":"UL Listed Fire Pipe - UNIASEN","og_url":"https:\/\/uniasen.com\/it\/prodotti\/tubo-elencato-ul\/","og_site_name":"UNIASEN","article_modified_time":"2025-05-26T08:10:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uniasen.com\/products\/ul-listed-pipe\/","url":"https:\/\/uniasen.com\/products\/ul-listed-pipe\/","name":"UL Listed Fire Pipe - UNIASEN","isPartOf":{"@id":"https:\/\/uniasen.com\/#website"},"datePublished":"2025-05-26T08:03:46+00:00","dateModified":"2025-05-26T08:10:13+00:00","breadcrumb":{"@id":"https:\/\/uniasen.com\/products\/ul-listed-pipe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniasen.com\/products\/ul-listed-pipe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uniasen.com\/products\/ul-listed-pipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uniasen.com\/"},{"@type":"ListItem","position":2,"name":"products","item":"https:\/\/uniasen.com\/products\/"},{"@type":"ListItem","position":3,"name":"UL Listed Fire Pipe"}]},{"@type":"WebSite","@id":"https:\/\/uniasen.com\/#website","url":"https:\/\/uniasen.com\/","name":"UNIASEN","description":"","publisher":{"@id":"https:\/\/uniasen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniasen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/uniasen.com\/#organization","name":"UniAsen","alternateName":"UniAsen (Tianjin) Co., Ltd.","url":"https:\/\/uniasen.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/uniasen.com\/#\/schema\/logo\/image\/","url":"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp","contentUrl":"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp","width":300,"height":300,"caption":"UniAsen"},"image":{"@id":"https:\/\/uniasen.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/pages\/5538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/comments?post=5538"}],"version-history":[{"count":14,"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/pages\/5538\/revisions"}],"predecessor-version":[{"id":5560,"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/pages\/5538\/revisions\/5560"}],"up":[{"embeddable":true,"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/pages\/912"}],"wp:attachment":[{"href":"https:\/\/uniasen.com\/it\/wp-json\/wp\/v2\/media?parent=5538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}