{"id":2803,"date":"2023-10-18T16:32:54","date_gmt":"2023-10-18T08:32:54","guid":{"rendered":"https:\/\/uniasen.com\/?page_id=2803"},"modified":"2024-09-05T11:43:30","modified_gmt":"2024-09-05T03:43:30","slug":"astm-a589","status":"publish","type":"page","link":"https:\/\/uniasen.com\/es\/estandares\/astm-a589\/","title":{"rendered":"ASTM A589\/A589M"},"content":{"rendered":"<div id=\"page-header-1364618803\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark featured-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap\" >\n              <div class=\"title-wrapper flex-col text-left medium-text-center\">\n          <h1 class=\"entry-title mb-0\">\n            ASTM A589\/A589M          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col flex-right text-right medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div>\n\n     \n<style>\n#page-header-1364618803 .title-bg {\n  background-image: url(https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-carbon-steel-pipe-manufacturer-header.webp);\n}\n<\/style>\n  <\/div>\n    <\/div>\n  \n\t<div id=\"gap-570961819\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-570961819 {\n  padding-top: 4%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section\" id=\"section_132561289\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-127887418\">\n\n\t<div id=\"col-709009557\" class=\"col medium-11 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_448107730\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp\" class=\"attachment-original size-original\" alt=\"API 5L tuber\u00eda de l\u00ednea de gas de acero al carbono erw f\u00e1brica de tuber\u00edas\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp 1000w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory-300x225.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory-768x576.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_448107730 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1413976519\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>ASTM A589<\/h2>\n<p><strong>Descripci\u00f3n general est\u00e1ndar:<br \/><\/strong>ASTM A589 es una especificaci\u00f3n que cubre las tuber\u00edas de acero al carbono sin soldadura y soldadas para pozos de agua. Esboza los requisitos para diferentes grados de tuber\u00eda de acero adecuada para la instalaci\u00f3n en pozos de agua,. La tuber\u00eda debe soportar la presi\u00f3n y las condiciones ambientales habituales.<\/p>\n<p><strong>Materiales principales:<br \/><\/strong>Acero carbono<\/p>\n<p><strong>\u00c1mbito de aplicaci\u00f3n:<br \/><\/strong>La norma ASTM A589 se utiliza en la construcci\u00f3n de pozos de agua. La tuber\u00eda de acero al carbono se utiliza como revestimiento o tuber\u00eda. Soporta la estructura del pozo y garantiza un suministro de agua seguro y eficiente.<\/p>\n<a href=\"#is-pop\" class=\"button primary\"  style=\"border-radius:10px;\">\n\t\t<span>Solicitar presupuesto<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_132561289 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1740908375\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-415733778\">\n\n\t<div id=\"col-1856421055\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Especificaci\u00f3n ASTM A589<\/h2>\n<table>\n<thead>\n<tr>\n<th>Norma ASTM<\/th>\n<th>\u00a0<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Procedimiento<\/td>\n<td><span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/uniasen.com\/es\/productos\/tubo-erw\/\">REG<\/a><\/span>, <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/uniasen.com\/es\/productos\/tubo-sin-costura\/\">SMLS<\/a><\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">Dimensiones<\/td>\n<td>33,4 mm -323,9 mm<\/td>\n<\/tr>\n<tr>\n<td>1&#8243; &#8211; 12&#8243;<\/td>\n<\/tr>\n<tr>\n<td>DN25 - DN300<\/td>\n<\/tr>\n<tr>\n<td>Espesor<\/td>\n<td>3,38-9,53 mm<\/td>\n<\/tr>\n<tr>\n<td>Unidad de longitud<\/td>\n<td>longitud de rango aleatorio o longitudes especiales<\/td>\n<\/tr>\n<tr>\n<td>Grado de acero<\/td>\n<td>GRA GRB<\/td>\n<\/tr>\n<tr>\n<td>Revestimiento de la superficie<\/td>\n<td>Barnizado, engrase, galvanizado en caliente<\/td>\n<\/tr>\n<tr>\n<td>Tipo de extremo<\/td>\n<td>Corte cuadrado, Liso, Biselado, Roscado, Encastre<\/td>\n<\/tr>\n<tr>\n<td>M\u00e9todo conjunto<\/td>\n<td>Montaje, brida, acoplamiento, abrazadera, hombro de tuber\u00eda, soldadura<\/td>\n<\/tr>\n<tr>\n<td>Mecanizado de tuber\u00edas<\/td>\n<td>Soldadura, plegado, perforaci\u00f3n, punzonado, estampado, ahusamiento, abocardado, expansi\u00f3n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1740908375 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1891707898\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1755971870\">\n\n\t<div id=\"col-2104654945\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Dimensi\u00f3n<\/h2>\n<table>\n<tbody>\n<tr>\n<td width=\"138\">Di\u00e1metro exterior<\/td>\n<td colspan=\"3\" width=\"246\">Espesor de pared<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">(mm)<\/td>\n<td colspan=\"3\" width=\"246\">(mm)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"384\">Tuber\u00eda de impulsi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">168.3<\/td>\n<td width=\"82\">7.11<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">219.1<\/td>\n<td width=\"82\">7.04<\/td>\n<td width=\"82\">8.18<\/td>\n<td width=\"82\">8.99<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">273.1<\/td>\n<td width=\"82\">7.09<\/td>\n<td width=\"82\">7.8<\/td>\n<td width=\"82\">9.27<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">323.9<\/td>\n<td width=\"82\">8.38<\/td>\n<td width=\"82\">9.53<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">355.6<\/td>\n<td width=\"82\">9.53<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">406.4<\/td>\n<td width=\"82\">9.53<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"384\">Tuber\u00eda escariada y derivada para pozos de agua<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">33.4<\/td>\n<td width=\"82\">3.38<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">42.2<\/td>\n<td width=\"82\">3.56<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">48.3<\/td>\n<td width=\"82\">3.68<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">60.3<\/td>\n<td width=\"82\">3.91<\/td>\n<td width=\"82\">4.24<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">73<\/td>\n<td width=\"82\">5.16<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">88.9<\/td>\n<td width=\"82\">5.49<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">101.6<\/td>\n<td width=\"82\">5.74<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">114.3<\/td>\n<td width=\"82\">6.02<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">141.3<\/td>\n<td width=\"82\">6.55<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">168.3<\/td>\n<td width=\"82\">7.11<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">219.1<\/td>\n<td width=\"82\">8.18<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">273.1<\/td>\n<td width=\"82\">9.271<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">323.9<\/td>\n<td width=\"82\">9.525<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"384\">Tuber\u00eda de pozo impulsada<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">33.40<\/td>\n<td width=\"82\">3.38<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">42.16<\/td>\n<td width=\"82\">3.56<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">48.26<\/td>\n<td width=\"82\">3.68<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">60.33<\/td>\n<td width=\"82\">3.91<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"4\" width=\"384\">Revestimiento de pozos de agua<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">88.9<\/td>\n<td width=\"82\">3.18<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">101.6<\/td>\n<td width=\"82\">3.40<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">114.3<\/td>\n<td width=\"82\">3.61<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">139.7<\/td>\n<td width=\"82\">3.91<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">152.4<\/td>\n<td width=\"82\">4.17<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">168.3<\/td>\n<td width=\"82\">4.70<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"138\">219.1<\/td>\n<td width=\"82\">4.78<\/td>\n<td width=\"82\">&#8211;<\/td>\n<td width=\"82\">&#8211;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1891707898 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_751625540\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1372430613\">\n\n\t<div id=\"col-1922657737\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Requisito qu\u00edmico<\/h2>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-139373154\">\n\n\t<div id=\"col-377657059\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<table width=\"379\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"379\">Composici\u00f3n qu\u00edmica<\/td>\n<\/tr>\n<tr>\n<td width=\"201\">Elemento<\/td>\n<td width=\"178\">Composici\u00f3n, %<\/td>\n<\/tr>\n<tr>\n<td width=\"201\">F\u00f3sforo, m\u00e1x.<\/td>\n<td width=\"178\">0.050<\/td>\n<\/tr>\n<tr>\n<td width=\"201\">Azufre, m\u00e1x.<\/td>\n<td width=\"178\">0.060<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_751625540 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_833896328\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-2014238036\">\n\n\t<div id=\"col-1668837000\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Requisito mec\u00e1nico<\/h2>\n<p>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td colspan=\"4\" width=\"533\">Requisitos de tracci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"216\">Propiedades mec\u00e1nicas<\/td>\n<td width=\"104\">Soldado a tope<\/td>\n<td width=\"108\">Grado A<\/td>\n<td width=\"105\">Grado B<\/td>\n<\/tr>\n<tr>\n<td width=\"216\">Resistencia a la tracci\u00f3n, m\u00edn.,<br \/>psi (MPa)<\/td>\n<td width=\"104\">48 000 (330)<\/td>\n<td width=\"108\">48 000 (330)<\/td>\n<td width=\"105\">60 000 (415)<\/td>\n<\/tr>\n<tr>\n<td width=\"216\">L\u00edmite el\u00e1stico, m\u00edn,<br \/>psi (MPa)<\/td>\n<td width=\"104\">30 000 (205)<\/td>\n<td width=\"108\">30 000 (205)<\/td>\n<td width=\"105\">35 000 (240)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_833896328 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1464151083\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-63979636\">\n\n\t<div id=\"col-1735054341\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>\u00bfPor qu\u00e9 elegir UNIASEN?<\/h2>\n<ul>\n<li>Nos especializamos en tubos de acero est\u00e1ndar ASTM A589\/A589M, que son soluciones de primera calidad para sus necesidades de pozos de agua. Disponibles en versiones con y sin costura, estos tubos de acero al carbono est\u00e1n dise\u00f1ados para ser fuertes, duraderos y fiables.<\/li>\n<li>Nuestra l\u00ednea de productos incluye cuatro tipos de tuber\u00edas: Tipo I (tuber\u00eda de impulsi\u00f3n), Tipo II (tuber\u00eda de expansi\u00f3n y deriva de pozos de agua), Tipo III (tuber\u00eda de impulsi\u00f3n de pozos) y Tipo IV (tuber\u00eda de revestimiento de pozos de agua). Cada tipo de tuber\u00eda est\u00e1 cuidadosamente dise\u00f1ado, y usted puede esperar un flujo de agua mejorado, fugas reducidas y una mayor estabilidad del pozo.<\/li>\n<li>Utilizamos procesos de solera abierta, horno el\u00e9ctrico u ox\u00edgeno b\u00e1sico. Garantizan la m\u00e1xima calidad del acero.<\/li>\n<li>Nuestros tubos tienen distintos revestimientos superficiales para una mayor protecci\u00f3n contra la corrosi\u00f3n y el desgaste. Ofrecemos extremos lisos, roscados y acoplados para conexiones f\u00e1ciles y seguras.<\/li>\n<li>Nuestros m\u00e9todos de conexi\u00f3n est\u00e1n dise\u00f1ados para ofrecer durabilidad y un rendimiento a prueba de fugas. Tambi\u00e9n ofrecemos servicios de mecanizado para necesidades de tuber\u00edas personalizadas.<\/li>\n<li>Nuestros tubos ASTM A589\/A589M se someten a pruebas de tracci\u00f3n, tensi\u00f3n e hidrost\u00e1ticas para garantizar que cumplen estos requisitos.<\/li>\n<\/ul>\n<a href=\"#is-pop\" class=\"button primary\"  style=\"border-radius:10px;\">\n\t\t<span>Solicitar presupuesto<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1900100953\" class=\"col medium-11 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-907736730\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1670\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate.webp\" class=\"bg\" alt=\"Puerta de f\u00e1brica UNIASEN\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate.webp 2500w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate-300x200.webp 300w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate-1030x688.webp 1030w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate-768x513.webp 768w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate-1536x1026.webp 1536w, https:\/\/uniasen.com\/wp-content\/uploads\/2024\/03\/UNIASEN-factory-gate-2048x1368.webp 2048w\" sizes=\"auto, (max-width: 2500px) 100vw, 2500px\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-171075626\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"video-button-wrapper\" style=\"font-size:200%\"><a href=\"https:\/\/www.youtube.com\/watch?v=oDiJnYyLsz4\" class=\"button open-video icon circle is-outline is-xlarge\"><i class=\"icon-play\" style=\"font-size:1.5em;\" ><\/i><\/a><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-171075626 {\n  width: 60%;\n}\n#text-box-171075626 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-907736730 {\n  padding-top: 56.25%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1464151083 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgba(231, 238, 241, 0.238);\n}\n@media (min-width:550px) {\n  #section_1464151083 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1275750704\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1275750704 {\n  padding-top: 3%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section\" id=\"section_1593322866\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-2131090710\">\n\n\n\t<div id=\"col-640256309\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1118446627\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-1465405402\">\n\n\n\t<div id=\"col-824433644\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1595197574\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/productos\/tubo-erw\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe.webp\" class=\"attachment-original size-original\" alt=\"Fabricante de tubos ERW de China\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-Carbon-Steel-Welded-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1595197574 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-537118478\" class=\"text\">\n\t\t\n\n<p><strong>Tubo soldado<\/strong><\/p>\n\t\t\n<style>\n#text-537118478 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-537118478 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1844138194\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_532543169\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/productos\/tubo-de-sierra\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe.webp\" class=\"attachment-original size-original\" alt=\"Fabricante y proveedor de tubos de acero para sierra.\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-spiral-welded-pipe-SSAW-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_532543169 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-621917312\" class=\"text\">\n\t\t\n\n<p><strong>Tuber\u00eda de acero SAW<\/strong><\/p>\n\t\t\n<style>\n#text-621917312 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-621917312 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1695679168\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_167476135\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/productos\/secciones-huecas\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier.webp\" class=\"attachment-original size-original\" alt=\"secci\u00f3n hueca de acero-secci\u00f3n estructural hueca-Uniasen\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-hollow-structural-section-manufacturer-and-supplier-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_167476135 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2412532326\" class=\"text\">\n\t\t\n\n<p><strong>Secci\u00f3n estructural hueca<\/strong><\/p>\n\t\t\n<style>\n#text-2412532326 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2412532326 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1000267860\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_286851024\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/productos\/tubo-sin-costura\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe.webp\" class=\"attachment-original size-original\" alt=\"tubo de acero sin costura-SMLS Pipe\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-seamless-carbon-steel-pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_286851024 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-1788767674\" class=\"text\">\n\t\t\n\n<p><strong>Tuber\u00eda de acero sin costura<\/strong><\/p>\n\t\t\n<style>\n#text-1788767674 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-1788767674 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1099262613\">\n\n\n\t<div id=\"col-135773290\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1796829315\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/productos\/accesorios-de-tuberia\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer.webp\" class=\"attachment-original size-original\" alt=\"accesorios de tuber\u00eda de China-accesorios de tuber\u00eda de acero al carbono\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-pipe-fitting-manufacturer-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1796829315 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-1887294531\" class=\"text\">\n\t\t\n\n<p><strong>Accesorios para tuber\u00edas<\/strong><\/p>\n\t\t\n<style>\n#text-1887294531 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-1887294531 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-889191551\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_530072856\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/steel-pipe-standards\/fire-sprinkler-pipe\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-fire-sprinkler-pipe-supplier-1-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_530072856 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2851355886\" class=\"text\">\n\t\t\n\n<p><strong>Tuber\u00eda de rociadores contra incendios<\/strong><\/p>\n\t\t\n<style>\n#text-2851355886 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-2851355886 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1766664076\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1788899303\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/steel-pipe-standards\/line-pipe\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-line-pipe-manufacturer-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1788899303 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3489874998\" class=\"text\">\n\t\t\n\n<p><strong>Tuberia<\/strong><\/p>\n\n\t\t\n<style>\n#text-3489874998 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-3489874998 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1616963416\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1252900896\">\n\t\t<a class=\"\" href=\"https:\/\/uniasen.com\/es\/steel-pipe-standards\/astm-a106\/\" target=\"_blank\" rel=\"noopener\" >\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3-hover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe.webp 600w, https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/Uniasen-ASTM-A106-Seamless-Carbon-Steel-Pipe-300x200.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1252900896 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-1530865713\" class=\"text\">\n\t\t\n\n<p><strong>Tuber\u00eda de acero sin costura ASTM A106<\/strong><\/p>\n\t\t\n<style>\n#text-1530865713 {\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-1530865713 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1593322866 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":4708,"parent":2187,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-2803","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASTM A589 Seamless and Welded Carbon Steel Pipe<\/title>\n<meta name=\"description\" content=\"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2803\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTM A589 Seamless and Welded Carbon Steel Pipe\" \/>\n<meta property=\"og:description\" content=\"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniasen.com\/es\/estandares\/astm-a589\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIASEN\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T03:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/\",\"url\":\"https:\/\/uniasen.com\/standards\/astm-a589\/\",\"name\":\"ASTM A589 Seamless and Welded Carbon Steel Pipe\",\"isPartOf\":{\"@id\":\"https:\/\/uniasen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp\",\"datePublished\":\"2023-10-18T08:32:54+00:00\",\"dateModified\":\"2024-09-05T03:43:30+00:00\",\"description\":\"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.\",\"breadcrumb\":{\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uniasen.com\/standards\/astm-a589\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage\",\"url\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp\",\"contentUrl\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp\",\"width\":1000,\"height\":750,\"caption\":\"API 5L gas line pipe carbon steel erw pipe factory\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uniasen.com\/standards\/astm-a589\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/uniasen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Standard\",\"item\":\"https:\/\/uniasen.com\/standards\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ASTM A589\/A589M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uniasen.com\/#website\",\"url\":\"https:\/\/uniasen.com\/\",\"name\":\"UNIASEN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/uniasen.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uniasen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/uniasen.com\/#organization\",\"name\":\"UniAsen\",\"alternateName\":\"UniAsen (Tianjin) Co., Ltd.\",\"url\":\"https:\/\/uniasen.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/uniasen.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp\",\"contentUrl\":\"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp\",\"width\":300,\"height\":300,\"caption\":\"UniAsen\"},\"image\":{\"@id\":\"https:\/\/uniasen.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTM A589 Seamless and Welded Carbon Steel Pipe","description":"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2803\/","og_locale":"es_ES","og_type":"article","og_title":"ASTM A589 Seamless and Welded Carbon Steel Pipe","og_description":"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.","og_url":"https:\/\/uniasen.com\/es\/estandares\/astm-a589\/","og_site_name":"UNIASEN","article_modified_time":"2024-09-05T03:43:30+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uniasen.com\/standards\/astm-a589\/","url":"https:\/\/uniasen.com\/standards\/astm-a589\/","name":"ASTM A589 Seamless and Welded Carbon Steel Pipe","isPartOf":{"@id":"https:\/\/uniasen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage"},"image":{"@id":"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage"},"thumbnailUrl":"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp","datePublished":"2023-10-18T08:32:54+00:00","dateModified":"2024-09-05T03:43:30+00:00","description":"ASTM A589 Seamless and Welded Carbon Steel Pipe is designed for high-pressure service, offering superior durability and strength. Ideal for use in water wells, structural applications, and industrial projects, this carbon steel pipe meets rigorous standards for performance and reliability.","breadcrumb":{"@id":"https:\/\/uniasen.com\/standards\/astm-a589\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniasen.com\/standards\/astm-a589\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uniasen.com\/standards\/astm-a589\/#primaryimage","url":"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp","contentUrl":"https:\/\/uniasen.com\/wp-content\/uploads\/2024\/08\/API_5L_gas_line_pipe_carbon_steel_erw_pipe_factory.webp","width":1000,"height":750,"caption":"API 5L gas line pipe carbon steel erw pipe factory"},{"@type":"BreadcrumbList","@id":"https:\/\/uniasen.com\/standards\/astm-a589\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uniasen.com\/"},{"@type":"ListItem","position":2,"name":"Standard","item":"https:\/\/uniasen.com\/standards\/"},{"@type":"ListItem","position":3,"name":"ASTM A589\/A589M"}]},{"@type":"WebSite","@id":"https:\/\/uniasen.com\/#website","url":"https:\/\/uniasen.com\/","name":"UNIASEN","description":"","publisher":{"@id":"https:\/\/uniasen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniasen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/uniasen.com\/#organization","name":"UniAsen","alternateName":"UniAsen (Tianjin) Co., Ltd.","url":"https:\/\/uniasen.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uniasen.com\/#\/schema\/logo\/image\/","url":"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp","contentUrl":"https:\/\/uniasen.com\/wp-content\/uploads\/2023\/11\/UNIASEN-carbon-steel-supplier-and-expertor-in-china-LOGO.webp","width":300,"height":300,"caption":"UniAsen"},"image":{"@id":"https:\/\/uniasen.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":8,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2803\/revisions"}],"predecessor-version":[{"id":4743,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2803\/revisions\/4743"}],"up":[{"embeddable":true,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/pages\/2187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/media\/4708"}],"wp:attachment":[{"href":"https:\/\/uniasen.com\/es\/wp-json\/wp\/v2\/media?parent=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}